{"id":55423,"count":1,"description":"","link":"https:\/\/staging.cined.dev\/es\/tag\/hacia-adelante\/","name":"hacia adelante","slug":"hacia-adelante","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.10 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>hacia adelante<\/title>\n<meta name=\"description\" content=\"hacia adelante,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/staging.cined.dev\/es\/tag\/hacia-adelante\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"hacia adelante\" \/>\n<meta property=\"og:description\" content=\"hacia adelante,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.cined.dev\/es\/tag\/hacia-adelante\/\" \/>\n<meta property=\"og:site_name\" content=\"CineD\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@c5dnews\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/staging.cined.dev\\\/es\\\/tag\\\/hacia-adelante\\\/\",\"url\":\"https:\\\/\\\/staging.cined.dev\\\/es\\\/tag\\\/hacia-adelante\\\/\",\"name\":\"hacia adelante\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cined.com\\\/#website\"},\"description\":\"hacia adelante,\",\"inLanguage\":\"es-ES\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cined.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cined.com\\\/\",\"name\":\"CineD\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cined.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cined.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cined.com\\\/#organization\",\"name\":\"CineD\",\"url\":\"https:\\\/\\\/www.cined.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.cined.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.cined.dev\\\/content\\\/uploads\\\/2020\\\/08\\\/logo_email.jpg\",\"contentUrl\":\"https:\\\/\\\/staging.cined.dev\\\/content\\\/uploads\\\/2020\\\/08\\\/logo_email.jpg\",\"width\":313,\"height\":285,\"caption\":\"CineD\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cined.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/C5Dnews\",\"https:\\\/\\\/x.com\\\/c5dnews\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/cinema5Dnews\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"hacia adelante","description":"hacia adelante,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/staging.cined.dev\/es\/tag\/hacia-adelante\/","og_locale":"es_ES","og_type":"article","og_title":"hacia adelante","og_description":"hacia adelante,","og_url":"https:\/\/staging.cined.dev\/es\/tag\/hacia-adelante\/","og_site_name":"CineD","twitter_card":"summary_large_image","twitter_site":"@c5dnews","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/staging.cined.dev\/es\/tag\/hacia-adelante\/","url":"https:\/\/staging.cined.dev\/es\/tag\/hacia-adelante\/","name":"hacia adelante","isPartOf":{"@id":"https:\/\/www.cined.com\/#website"},"description":"hacia adelante,","inLanguage":"es-ES"},{"@type":"WebSite","@id":"https:\/\/www.cined.com\/#website","url":"https:\/\/www.cined.com\/","name":"CineD","description":"","publisher":{"@id":"https:\/\/www.cined.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cined.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.cined.com\/#organization","name":"CineD","url":"https:\/\/www.cined.com\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.cined.com\/#\/schema\/logo\/image\/","url":"https:\/\/staging.cined.dev\/content\/uploads\/2020\/08\/logo_email.jpg","contentUrl":"https:\/\/staging.cined.dev\/content\/uploads\/2020\/08\/logo_email.jpg","width":313,"height":285,"caption":"CineD"},"image":{"@id":"https:\/\/www.cined.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/C5Dnews","https:\/\/x.com\/c5dnews","https:\/\/www.youtube.com\/user\/cinema5Dnews"]}]}},"_links":{"self":[{"href":"https:\/\/staging.cined.dev\/es\/wp-json\/wp\/v2\/tags\/55423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.cined.dev\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/staging.cined.dev\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/staging.cined.dev\/es\/wp-json\/wp\/v2\/posts?tags=55423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}